{"id":1147,"date":"2025-05-08T00:00:00","date_gmt":"2025-05-07T22:00:00","guid":{"rendered":"https:\/\/professionals.sitgesanytime.com\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/"},"modified":"2025-05-08T00:00:00","modified_gmt":"2025-05-07T22:00:00","slug":"la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio","status":"publish","type":"post","link":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/","title":{"rendered":"La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio"},"content":{"rendered":"<p data-start=\"112\" data-end=\"727\">\u00a0La cita tradicional con la fotograf\u00eda vuelve a Sitges del 17 de mayo al 1 de junio. El Fotomaig llega este 2025 a la 21\u00aa edici\u00f3n para poner en valor nuevamente el arte fotogr\u00e1fico como medio de expresi\u00f3n, que muestra diferentes realidades, emociones y sentimientos. La Secci\u00f3n Fotogr\u00e1fica del Grup d\u2019Estudis Sitgetans (SFGES), con la colaboraci\u00f3n del Ayuntamiento de Sitges y entidades culturales, sociales, educativas y deportivas de la villa, impulsan esta iniciativa que este a\u00f1o permitir\u00e1 descubrir 477 fotograf\u00edas que tratan diferentes tem\u00e1ticas a trav\u00e9s de 12 exposiciones instaladas en 11 espacios de Sitges.<\/p>\n<p data-start=\"729\" data-end=\"730\">\u00a0<\/p>\n<p data-start=\"732\" data-end=\"966\">Los amantes de la fotograf\u00eda y los curiosos tienen un punto de encuentro a trav\u00e9s de este evento que, adem\u00e1s de muestras fotogr\u00e1ficas, tambi\u00e9n incluye otras actividades como proyecciones de fotograf\u00edas y audiovisuales, charlas y cine.<\/p>\n<p data-start=\"968\" data-end=\"969\">\u00a0<\/p>\n<p data-start=\"971\" data-end=\"1079\">La inauguraci\u00f3n del Fotomaig ser\u00e1 el 17 de mayo a las 19 h en el Espai Cultural Pere St\u00e4mpfli, sede del GES.<\/p>\n<p data-start=\"1081\" data-end=\"1082\">\u00a0<\/p>\n<p data-start=\"1084\" data-end=\"1115\"><strong>Exposiciones dedicadas a Sitges<\/strong><\/p>\n<p data-start=\"1120\" data-end=\"1449\">En el Mercado Municipal se podr\u00e1n ver 28 im\u00e1genes distintas de la Secci\u00f3n Fotogr\u00e1fica del Grup d\u2019Estudis Sitgetans con el t\u00edtulo Estimat Sitges. La misma entidad tambi\u00e9n mostrar\u00e1 en el vest\u00edbulo del Hospital Sant Joan Baptista de Sitges 26 instant\u00e1neas de diferentes rincones de la villa con el t\u00edtulo Sitges, diferentes miradas.<\/p>\n<p data-start=\"1451\" data-end=\"1452\">\u00a0<\/p>\n<p data-start=\"1454\" data-end=\"1663\">Adem\u00e1s, la SFGES tambi\u00e9n complementa estas propuestas con la colectiva que instalar\u00e1 en el Miramar-Centre Cultural y que este a\u00f1o estar\u00e1 formada por 35 autores que exhibir\u00e1n 4 fotograf\u00edas de la misma tem\u00e1tica.<\/p>\n<p data-start=\"1665\" data-end=\"1666\">\u00a0<\/p>\n<p data-start=\"1668\" data-end=\"1758\"><strong>El fot\u00f3grafo Pep Escoda expone su obra en la capilla de las artes de la Fundaci\u00f3 Ave Maria<\/strong><\/p>\n<p data-start=\"1763\" data-end=\"2101\">El fot\u00f3grafo tarraconense Pep Escoda trabaja profesionalmente desde 1990 y est\u00e1 especializado en la fotograf\u00eda de interiorismo, arquitectura y retrato. Ahora una selecci\u00f3n de sus retratos se podr\u00e1 ver en la capilla de las artes de la Fundaci\u00f3 Ave Maria y tambi\u00e9n ofrecer\u00e1 una visita y charla sobre su muestra el 24 de mayo a las 19 horas.<\/p>\n<p data-start=\"2103\" data-end=\"2104\">\u00a0<\/p>\n<p data-start=\"2106\" data-end=\"2286\">A lo largo de su trayectoria ha sido galardonado con veinte premios, ha publicado sus fotograf\u00edas en m\u00e1s de 140 libros y ha expuesto tanto individualmente como de manera colectiva.<\/p>\n<p data-start=\"2288\" data-end=\"2289\">\u00a0<\/p>\n<p data-start=\"2291\" data-end=\"2354\"><strong>Lee, un biopic para acercar la famosa fot\u00f3grafa al gran p\u00fablico<\/strong><\/p>\n<p data-start=\"2359\" data-end=\"2809\">En el marco del Fotomaig se proyectar\u00e1 la pel\u00edcula Lee, un biopic que narra la historia de la famosa fot\u00f3grafa Elizabeth \u2018Lee\u2019 Miller, interpretada por Kate Winslet, que fotografi\u00f3 los momentos m\u00e1s cruciales del siglo XX. Esta pel\u00edcula sobre la modelo que se convirti\u00f3 en una reconocida corresponsal de guerra para Vogue durante la Segunda Guerra Mundial se podr\u00e1 ver desde el 15 de mayo y hasta el 19 de mayo en diversos horarios en el Cinema Prado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Fotomaig llega a la 21\u00aa edici\u00f3n con m\u00e1s de 400 fotograf\u00edas distribuidas en 12 exposiciones. Todas las muestras son de entrada gratuita.<\/p>\n","protected":false},"author":1,"featured_media":1145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio - Sitges Professionals<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio - Sitges Professionals\" \/>\n<meta property=\"og:description\" content=\"El Fotomaig llega a la 21\u00aa edici\u00f3n con m\u00e1s de 400 fotograf\u00edas distribuidas en 12 exposiciones. Todas las muestras son de entrada gratuita.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/\" \/>\n<meta property=\"og:site_name\" content=\"Sitges Professionals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/turismedesitges\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-07T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"minsk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"minsk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/\"},\"author\":{\"name\":\"minsk\",\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/#\\\/schema\\\/person\\\/235e5f4a44e48dabf33c297c448ac7ff\"},\"headline\":\"La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio\",\"datePublished\":\"2025-05-07T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/\"},\"wordCount\":483,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/fotomaig-4.jpeg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/\",\"url\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/\",\"name\":\"La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio - Sitges Professionals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/fotomaig-4.jpeg\",\"datePublished\":\"2025-05-07T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/fotomaig-4.jpeg\",\"contentUrl\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/fotomaig-4.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/\",\"name\":\"Sitges Professionals\",\"description\":\"\u00c1rea Profesional Turismo de Sitges\",\"publisher\":{\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/#organization\",\"name\":\"Turisme Ajuntament de Sitges\",\"url\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/turisme-sitges-1-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/turisme-sitges-1-scaled.webp\",\"width\":2560,\"height\":1440,\"caption\":\"Turisme Ajuntament de Sitges\"},\"image\":{\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/turismedesitges\",\"https:\\\/\\\/instagram.com\\\/sitgesturisme\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC2G69AN3eOIDEDwnB84GBpw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/#\\\/schema\\\/person\\\/235e5f4a44e48dabf33c297c448ac7ff\",\"name\":\"minsk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dc993d55c4ec102c60ca929dd2b8e21aeca5606b4c466e4bfefd1c8955e9d58?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dc993d55c4ec102c60ca929dd2b8e21aeca5606b4c466e4bfefd1c8955e9d58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dc993d55c4ec102c60ca929dd2b8e21aeca5606b4c466e4bfefd1c8955e9d58?s=96&d=mm&r=g\",\"caption\":\"minsk\"},\"sameAs\":[\"http:\\\/\\\/professionals.sitgesanytime.com\"],\"url\":\"https:\\\/\\\/professionals.sitgesanytime.com\\\/es\\\/author\\\/minsk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio - Sitges Professionals","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/","og_locale":"es_ES","og_type":"article","og_title":"La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio - Sitges Professionals","og_description":"El Fotomaig llega a la 21\u00aa edici\u00f3n con m\u00e1s de 400 fotograf\u00edas distribuidas en 12 exposiciones. Todas las muestras son de entrada gratuita.","og_url":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/","og_site_name":"Sitges Professionals","article_publisher":"https:\/\/www.facebook.com\/turismedesitges","article_published_time":"2025-05-07T22:00:00+00:00","author":"minsk","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"minsk","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/#article","isPartOf":{"@id":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/"},"author":{"name":"minsk","@id":"https:\/\/professionals.sitgesanytime.com\/es\/#\/schema\/person\/235e5f4a44e48dabf33c297c448ac7ff"},"headline":"La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio","datePublished":"2025-05-07T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/"},"wordCount":483,"commentCount":0,"publisher":{"@id":"https:\/\/professionals.sitgesanytime.com\/es\/#organization"},"image":{"@id":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/#primaryimage"},"thumbnailUrl":"https:\/\/professionals.sitgesanytime.com\/wp-content\/uploads\/2025\/05\/fotomaig-4.jpeg","articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/","url":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/","name":"La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio - Sitges Professionals","isPartOf":{"@id":"https:\/\/professionals.sitgesanytime.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/#primaryimage"},"image":{"@id":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/#primaryimage"},"thumbnailUrl":"https:\/\/professionals.sitgesanytime.com\/wp-content\/uploads\/2025\/05\/fotomaig-4.jpeg","datePublished":"2025-05-07T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/#primaryimage","url":"https:\/\/professionals.sitgesanytime.com\/wp-content\/uploads\/2025\/05\/fotomaig-4.jpeg","contentUrl":"https:\/\/professionals.sitgesanytime.com\/wp-content\/uploads\/2025\/05\/fotomaig-4.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/professionals.sitgesanytime.com\/es\/la-gran-cita-con-la-fotografia-se-celebrara-en-sitges-del-17-de-mayo-al-1-de-junio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/professionals.sitgesanytime.com\/es\/"},{"@type":"ListItem","position":2,"name":"La gran cita con la fotografia se celebrar\u00e0 en Sitges del 17 de mayo al 1 de junio"}]},{"@type":"WebSite","@id":"https:\/\/professionals.sitgesanytime.com\/es\/#website","url":"https:\/\/professionals.sitgesanytime.com\/es\/","name":"Sitges Professionals","description":"\u00c1rea Profesional Turismo de Sitges","publisher":{"@id":"https:\/\/professionals.sitgesanytime.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/professionals.sitgesanytime.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/professionals.sitgesanytime.com\/es\/#organization","name":"Turisme Ajuntament de Sitges","url":"https:\/\/professionals.sitgesanytime.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/professionals.sitgesanytime.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/professionals.sitgesanytime.com\/wp-content\/uploads\/2026\/06\/turisme-sitges-1-scaled.webp","contentUrl":"https:\/\/professionals.sitgesanytime.com\/wp-content\/uploads\/2026\/06\/turisme-sitges-1-scaled.webp","width":2560,"height":1440,"caption":"Turisme Ajuntament de Sitges"},"image":{"@id":"https:\/\/professionals.sitgesanytime.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/turismedesitges","https:\/\/instagram.com\/sitgesturisme","https:\/\/www.youtube.com\/channel\/UC2G69AN3eOIDEDwnB84GBpw"]},{"@type":"Person","@id":"https:\/\/professionals.sitgesanytime.com\/es\/#\/schema\/person\/235e5f4a44e48dabf33c297c448ac7ff","name":"minsk","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7dc993d55c4ec102c60ca929dd2b8e21aeca5606b4c466e4bfefd1c8955e9d58?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7dc993d55c4ec102c60ca929dd2b8e21aeca5606b4c466e4bfefd1c8955e9d58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7dc993d55c4ec102c60ca929dd2b8e21aeca5606b4c466e4bfefd1c8955e9d58?s=96&d=mm&r=g","caption":"minsk"},"sameAs":["http:\/\/professionals.sitgesanytime.com"],"url":"https:\/\/professionals.sitgesanytime.com\/es\/author\/minsk\/"}]}},"_links":{"self":[{"href":"https:\/\/professionals.sitgesanytime.com\/es\/wp-json\/wp\/v2\/posts\/1147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/professionals.sitgesanytime.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/professionals.sitgesanytime.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/professionals.sitgesanytime.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/professionals.sitgesanytime.com\/es\/wp-json\/wp\/v2\/comments?post=1147"}],"version-history":[{"count":0,"href":"https:\/\/professionals.sitgesanytime.com\/es\/wp-json\/wp\/v2\/posts\/1147\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/professionals.sitgesanytime.com\/es\/wp-json\/wp\/v2\/media\/1145"}],"wp:attachment":[{"href":"https:\/\/professionals.sitgesanytime.com\/es\/wp-json\/wp\/v2\/media?parent=1147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/professionals.sitgesanytime.com\/es\/wp-json\/wp\/v2\/categories?post=1147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/professionals.sitgesanytime.com\/es\/wp-json\/wp\/v2\/tags?post=1147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}